{"id":18462,"date":"2020-08-07T10:49:38","date_gmt":"2020-08-07T13:49:38","guid":{"rendered":"https:\/\/metropolitan.com.br\/?p=18462"},"modified":"2020-08-07T10:49:38","modified_gmt":"2020-08-07T13:49:38","slug":"7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan","status":"publish","type":"post","link":"https:\/\/metropolitan.com.br\/br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/","title":{"rendered":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan"},"content":{"rendered":"<p>\t\t\t\tA mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de <strong>gest\u00e3o de expatriados<\/strong>, pois existem muitos tr\u00e2mites que precisam ser providenciados.<\/p>\n<p>Ao escolher a Metropolitan \u00e9 poss\u00edvel ter acesso a todos os servi\u00e7os necess\u00e1rios e garantir que eles ter\u00e3o qualidade. Veja motivos para optar por ela.<\/p>\n<p>&nbsp;<\/p>\n<h2>1. Especializada em expatriados<\/h2>\n<p>A Metropolitan foi fundada em 1969 e desde ent\u00e3o cuida de expatriados, garantindo que eles e seus pertences cheguem ao destino em seguran\u00e7a. Ela se especializou nesse ramo e conhece bem como ele funciona, o que deve ser feito para que tudo ocorra conforme o planejado e as necessidades de seus clientes.<\/p>\n<p>&nbsp;<\/p>\n<h2>2. Empresa l\u00edder de transporte<\/h2>\n<p>Quando o assunto \u00e9 transporte, ela \u00e9 uma l\u00edder na Am\u00e9rica Latina, n\u00e3o apenas pela quantidade de bens transportados, mas, por sua qualidade.<\/p>\n<p>Ela possui certifica\u00e7\u00f5es para refor\u00e7ar a sua preocupa\u00e7\u00e3o com o servi\u00e7o prestado e constantemente realiza pesquisas internas e com os clientes para entender o n\u00edvel de satisfa\u00e7\u00e3o e o que pode ser melhorado.<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"broken_link\" href=\"https:\/\/materiais.metropolitan.com.br\/contato-metropolitan\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><img decoding=\"async\" class=\"alignnone wp-image-18437 size-full retinized\" src=\"https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_CONTATO-1.png\" sizes=\"(max-width: 2057px) 100vw, 2057px\" srcset=\"https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_CONTATO-1.png 2057w, https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_CONTATO-1-768x100.png 768w\" alt=\"\" width=\"2057\" height=\"267\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>3. Planejamento da gest\u00e3o de expatriado<\/h2>\n<p>Uma empresa completa, a Metropolitan presta um servi\u00e7o total quando o assunto \u00e9 planejamento da gest\u00e3o de expatriado.<\/p>\n<p>Ela cuida dos pertencentes do colaborador e garante que eles cheguem ao destino, como tamb\u00e9m orienta a empresa empregadora e o empregado de todo o processo e documentos.<\/p>\n<p>&nbsp;<\/p>\n<h2>4.Pol\u00edtica transparente para o expatriado<\/h2>\n<p>Uma das preocupa\u00e7\u00f5es \u00e9 que o colaborador n\u00e3o tenha surpresas desagrad\u00e1veis ao chegar no destino. Para isso apoia o RH para que sejam analisadas as expectativas do trabalhador, seu perfil profissional e\u00a0 estabelece padr\u00f5es para a nova designa\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2>5. Viagem de reconhecimento<\/h2>\n<p>Muitas empresas enviam o colaborador a outro pa\u00eds sem que ele conhe\u00e7a ou fa\u00e7a um reconhecimento. Isso pode ocorrer por inexperi\u00eancia, mas a Metropolitan cuida de toda a <strong>gest\u00e3o de expatriados<\/strong>, inclusive deste ponto.<\/p>\n<p>Presta um suporte a empresa e ao colaborador para que esse \u00faltimo tenha uma vis\u00e3o de seu novo local de resid\u00eancia, entenda os custos e facilidades. Ao mesmo tempo, garante que ele receba uma carta de oferta de explica\u00e7\u00e3o sobre sal\u00e1rio, benef\u00edcios, subs\u00eddios e outros.<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"broken_link\" href=\"https:\/\/materiais.metropolitan.com.br\/orcamento-de-mudanca\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><img decoding=\"async\" class=\"alignnone wp-image-18438 size-full retinized\" src=\"https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_OR\u00c7AMENTO-1.png\" sizes=\"(max-width: 2057px) 100vw, 2057px\" srcset=\"https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_OR\u00c7AMENTO-1.png 2057w, https:\/\/metropolitan.com.br\/wp-content\/uploads\/CTA_OR\u00c7AMENTO-1-768x100.png 768w\" alt=\"\" width=\"2057\" height=\"267\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2>6. Tr\u00e2mites burocr\u00e1ticos<\/h2>\n<p>A mudan\u00e7a do funcion\u00e1rio para a expatria\u00e7\u00e3o exige o cumprimento de tr\u00e2mites como providenciar a documenta\u00e7\u00e3o, o incluir na folha de pagamento, buscar uma resid\u00eancia, transportar a mudan\u00e7a, encontrar escola para os filhos, etc.<\/p>\n<p>J\u00e1 os repatriados precisar\u00e3o rescindir o contrato, transferir os filhos de escola, entregar o im\u00f3vel, transportar a mudan\u00e7a e entregar uma declara\u00e7\u00e3o ao Fisco.<\/p>\n<p>A Metropolitan \u00e9 especializada em <strong>gest\u00e3o de expatriados <\/strong>cuida de todos esses processos garantindo que eles possam se mudar para um novo pa\u00eds ou retornar ao seu.<\/p>\n<p>&nbsp;<\/p>\n<h2>7. Repatria\u00e7\u00e3o do colaborador<\/h2>\n<p>A <strong>gest\u00e3o de expatriados<\/strong> s\u00f3 fica completa quando o colaborador retorna ao seu local de origem. Todo o processo de repatria\u00e7\u00e3o receber\u00e1 a mesma aten\u00e7\u00e3o que no processo oposto e garantir\u00e1 que o ciclo se complete.<\/p>\n<p>A Metropolitan \u00e9 uma excelente op\u00e7\u00e3o para empresas e empregados, pois, garante um suporte total na <strong>gest\u00e3o de expatriados<\/strong>. Ela n\u00e3o apenas \u00e9 uma especialista no assunto como realiza seu trabalho com foco no cliente e qualidade.\t\t<\/p>","protected":false},"excerpt":{"rendered":"<p>A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites<\/p>","protected":false},"author":6,"featured_media":18464,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[49,50,51,52,53,54,55,56],"class_list":["post-18462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expatriacao","tag-empresa-lider-de-transporte","tag-especializada-em-expatriados","tag-gestao-de-expatriados","tag-planejamento-da-gestao-de-expatriado","tag-politica-transparente-para-o-expatriado","tag-repatriacao-do-colaborador","tag-tramites-burocraticos","tag-viagem-de-reconhecimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan<\/title>\n<meta name=\"description\" content=\"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metropolitan.com.br\/br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan\" \/>\n<meta property=\"og:description\" content=\"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metropolitan.com.br\/br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/\" \/>\n<meta property=\"og:site_name\" content=\"Metropolitan Transport\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-07T13:49:38+00:00\" \/>\n<meta name=\"author\" content=\"Transportes Metropolitanos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Transportes Metropolitanos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/\"},\"author\":{\"name\":\"Transportes Metropolitanos\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/#\\\/schema\\\/person\\\/b2a559a9828839e1db5ae2da9da57aac\"},\"headline\":\"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan\",\"datePublished\":\"2020-08-07T13:49:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/\"},\"wordCount\":576,\"image\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Empresa l\u00edder de transporte\",\"Especializada em expatriados\",\"gest\u00e3o de expatriados\",\"Planejamento da gest\u00e3o de expatriado\",\"Pol\u00edtica transparente para o expatriado\",\"Repatria\u00e7\u00e3o do colaborador\",\"Tr\u00e2mites burocr\u00e1ticos\",\"Viagem de reconhecimento\"],\"articleSection\":[\"Expatria\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/\",\"url\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/\",\"name\":\"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-08-07T13:49:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/#\\\/schema\\\/person\\\/b2a559a9828839e1db5ae2da9da57aac\"},\"description\":\"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/expatriacao\\\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metropolitan.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/\",\"name\":\"Metropolitan Transport\",\"description\":\"Making relocation a positively moving experience\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/en\\\/#\\\/schema\\\/person\\\/b2a559a9828839e1db5ae2da9da57aac\",\"name\":\"Transportes Metropolitanos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/metropolitan.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848\",\"url\":\"https:\\\/\\\/metropolitan.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848\",\"contentUrl\":\"https:\\\/\\\/metropolitan.com.br\\\/wp-content\\\/litespeed\\\/avatar\\\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848\",\"caption\":\"Transportes Metropolitanos\"},\"url\":\"https:\\\/\\\/metropolitan.com.br\\\/br\\\/author\\\/blackbeans\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan","description":"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metropolitan.com.br\/br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/","og_locale":"pt_BR","og_type":"article","og_title":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan","og_description":"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.","og_url":"https:\/\/metropolitan.com.br\/br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/","og_site_name":"Metropolitan Transport","article_published_time":"2020-08-07T13:49:38+00:00","author":"Transportes Metropolitanos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Transportes Metropolitanos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#article","isPartOf":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/"},"author":{"name":"Transportes Metropolitanos","@id":"https:\/\/metropolitan.com.br\/en\/#\/schema\/person\/b2a559a9828839e1db5ae2da9da57aac"},"headline":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan","datePublished":"2020-08-07T13:49:38+00:00","mainEntityOfPage":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/"},"wordCount":576,"image":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#primaryimage"},"thumbnailUrl":"","keywords":["Empresa l\u00edder de transporte","Especializada em expatriados","gest\u00e3o de expatriados","Planejamento da gest\u00e3o de expatriado","Pol\u00edtica transparente para o expatriado","Repatria\u00e7\u00e3o do colaborador","Tr\u00e2mites burocr\u00e1ticos","Viagem de reconhecimento"],"articleSection":["Expatria\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/","url":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/","name":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan","isPartOf":{"@id":"https:\/\/metropolitan.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#primaryimage"},"image":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-08-07T13:49:38+00:00","author":{"@id":"https:\/\/metropolitan.com.br\/en\/#\/schema\/person\/b2a559a9828839e1db5ae2da9da57aac"},"description":"A mudan\u00e7a dos colaboradores de pa\u00eds precisa ser feita por uma empresa de gest\u00e3o de expatriados, pois existem muitos tr\u00e2mites que precisam ser providenciados.","breadcrumb":{"@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/metropolitan.com.br\/expatriacao\/7-motivos-para-escolher-a-gestao-de-expatriados-da-metropolitan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metropolitan.com.br\/"},{"@type":"ListItem","position":2,"name":"7 Motivos para escolher a gest\u00e3o de Expatriados da Metropolitan"}]},{"@type":"WebSite","@id":"https:\/\/metropolitan.com.br\/en\/#website","url":"https:\/\/metropolitan.com.br\/en\/","name":"Metropolitan Transport","description":"Making relocation a positively moving experience","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metropolitan.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/metropolitan.com.br\/en\/#\/schema\/person\/b2a559a9828839e1db5ae2da9da57aac","name":"Transportes Metropolitanos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/metropolitan.com.br\/wp-content\/litespeed\/avatar\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848","url":"https:\/\/metropolitan.com.br\/wp-content\/litespeed\/avatar\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848","contentUrl":"https:\/\/metropolitan.com.br\/wp-content\/litespeed\/avatar\/d0a676f7344f0833ba95c6e85620132c.jpg?ver=1787685848","caption":"Transportes Metropolitanos"},"url":"https:\/\/metropolitan.com.br\/br\/author\/blackbeans\/"}]}},"_links":{"self":[{"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/posts\/18462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/comments?post=18462"}],"version-history":[{"count":0,"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/posts\/18462\/revisions"}],"wp:attachment":[{"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/media?parent=18462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/categories?post=18462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metropolitan.com.br\/br\/wp-json\/wp\/v2\/tags?post=18462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}